{"id":1221,"date":"2020-01-17T12:42:11","date_gmt":"2020-01-17T11:42:11","guid":{"rendered":"https:\/\/labozero.wordpress.com\/?p=1221"},"modified":"2020-01-17T12:42:11","modified_gmt":"2020-01-17T11:42:11","slug":"tricot-couture-danse-boxe-et-revolution","status":"publish","type":"post","link":"https:\/\/www.labozero.org\/index.php\/2020\/01\/17\/tricot-couture-danse-boxe-et-revolution\/","title":{"rendered":"Tricot, couture, danse, boxe et R\u00e9volution !"},"content":{"rendered":"<p style=\"text-align:center;\">Une semaine tr\u00e8s riche arrive ! Voil\u00e0 la programmation d\u00e9taill\u00e9e :<\/p>\n<p><strong>Samedi :<\/strong> RDV chez les copains de\u00a0 la DSXL de Romainville au 101 avenue Gaston Roussel, entre 15 et 19h pour :<\/p>\n<ul>\n<li>Profiter de la gratuiterie,<\/li>\n<li>Manger du th\u00e9 et des g\u00e2teaux faits avec amour et passion,<\/li>\n<li>R\u00e9parer ma platine vinyle au HackerSpace stp,<\/li>\n<li>Suivre l\u2019atelier photo des Bananas,<\/li>\n<li>Bricoler ton v\u00e9lo avec joie et plaisir,<\/li>\n<li>et faire du Go Go dancing avec Jo Jo<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p><strong>Dimanche<\/strong> chez nous \u00e0 Pantin, tenez vous bien :<\/p>\n<ul>\n<li>15\/21h atelier d\u2019auto-r\u00e9paration et de construction avec Michel<\/li>\n<li>15\/17h atelier de reprisage d\u00e9coratif de v\u00eatement avec Stephanie, apportez un v\u00eatement abim\u00e9\/tach\u00e9 ET atelier couture \u00d8d\u00e9chet<\/li>\n<li>15\/16h atelier de danse hip hop \u00ab\u00a0Waacking\u00a0\u00bb tous niveaux avec Annabelle.<\/li>\n<li>17\/19h boxe Anglaise f\u00e9minine avec Audrey et sa team (prix libre)<\/li>\n<li>17\/19h atelier tricot avec le gang des tricoteuses de Revons la culture de Noisy le sec (tous niveaux)<\/li>\n<li>tout l\u2019apr\u00e8s midi : tawashis minis et g\u00e9ants en autonomie<\/li>\n<li>boissons chaudes\/gouter\/cantoch\u2019 bio \u00e0 prix libre<\/li>\n<li>espace jeux pour les tout petits et ludoth\u00e8que \u00e0 dispo pour les plus grands.<\/li>\n<li>Points de collectes pour les midis du Mie et Un petit bagage d\u2019amour<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p><strong>Mardi<\/strong> \u00e0 Pantin :<\/p>\n<ul>\n<li>19\/21h Boxe Anglaise f\u00e9minine avec Audrey et sa team (prix libre)<\/li>\n<li>19\/21h Conf\u00e9rence d\u00e9bat avec le collectif \u00ab\u00a0Nous sommes Pantin\u00a0\u00bb sur les th\u00e8mes suivants : logement, immobilier, gentrification, sp\u00e9culation.<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p><strong>Jeudi<\/strong> \u00e0 Pantin :<\/p>\n<ul>\n<li>Distribution de l\u2019AMAP des 4 chemin<\/li>\n<li>18\/20h atelier d\u2019auto-r\u00e9paration et de construction avec Michel<\/li>\n<li>\u00a0tawashis minis et g\u00e9ants en autonomie<\/li>\n<li>boissons chaudes\/gouter\/cantoch\u2019 bio \u00e0 prix libre<\/li>\n<li>espace jeux pour les tout petits et ludoth\u00e8que \u00e0 dispo pour les plus grands.<\/li>\n<li>Points de collectes pour les midis du Mie et Un petit bagage d\u2019amour<\/li>\n<\/ul>\n<p style=\"text-align:center;\">ET :<\/p>\n<p style=\"text-align:center;\">Suite de nos soir\u00e9es de soutien aux gr\u00e9vistes, <strong>RDV \u00e0 20h30 pour le film<\/strong><\/p>\n<p style=\"text-align:center;\">et cantoch bio \u00e0 prix libre cette semaine :<\/p>\n<p style=\"text-align:center;\">Diffusion de \u00ab\u00a0l&rsquo;amour et la r\u00e9volution\u00a0\u00bb<\/p>\n<p style=\"text-align:center;\">de Yannis Youlountas.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-1223\" src=\"https:\/\/www.labozero.org\/wp-content\/uploads\/2020\/01\/external-content.duckduckgo.com_.jpg\" alt=\"external-content.duckduckgo.com\" width=\"1200\" height=\"1805\" srcset=\"https:\/\/www.labozero.org\/wp-content\/uploads\/2020\/01\/external-content.duckduckgo.com_.jpg 1200w, https:\/\/www.labozero.org\/wp-content\/uploads\/2020\/01\/external-content.duckduckgo.com_-199x300.jpg 199w, https:\/\/www.labozero.org\/wp-content\/uploads\/2020\/01\/external-content.duckduckgo.com_-681x1024.jpg 681w, https:\/\/www.labozero.org\/wp-content\/uploads\/2020\/01\/external-content.duckduckgo.com_-768x1155.jpg 768w, https:\/\/www.labozero.org\/wp-content\/uploads\/2020\/01\/external-content.duckduckgo.com_-1021x1536.jpg 1021w\" sizes=\"auto, (max-width: 1200px) 100vw, 1200px\" \/><\/p>\n<p>Super premi\u00e8re \u00e9dition hier soir, une trentaine de personnes et 178,60 euros de r\u00e9colt\u00e9s !<\/p>\n<p style=\"text-align:justify;\">On fera mieux la semaine prochaine, on compte sur vous !!! Passez l&rsquo;info, venez nombreux.<\/p>\n<p>&nbsp;<\/p>\n<p>Belle semaine \u00e0 toutes\/s<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Une semaine tr\u00e8s riche arrive ! Voil\u00e0 la programmation d\u00e9taill\u00e9e : Samedi : RDV chez les copains de\u00a0 la DSXL de Romainville au 101 avenue Gaston Roussel, entre 15 et 19h pour : Profiter de la gratuiterie, Manger du th\u00e9 et des g\u00e2teaux faits avec amour et passion, R\u00e9parer ma platine vinyle au HackerSpace stp, Suivre l\u2019atelier photo des Bananas, Bricoler ton v\u00e9lo avec joie et plaisir, et faire du Go Go dancing avec Jo Jo &nbsp; Dimanche chez nous \u00e0 Pantin, tenez vous bien : 15\/21h atelier d\u2019auto-r\u00e9paration et de construction avec Michel 15\/17h atelier de reprisage d\u00e9coratif de v\u00eatement avec Stephanie, apportez un v\u00eatement abim\u00e9\/tach\u00e9 ET atelier couture \u00d8d\u00e9chet 15\/16h atelier de danse hip hop \u00ab\u00a0Waacking\u00a0\u00bb tous niveaux avec Annabelle. 17\/19h boxe Anglaise f\u00e9minine avec Audrey et sa team (prix libre) 17\/19h atelier tricot avec le gang des tricoteuses de Revons la culture de Noisy le sec (tous niveaux) tout l\u2019apr\u00e8s midi : tawashis minis et g\u00e9ants en autonomie boissons chaudes\/gouter\/cantoch\u2019 bio \u00e0 prix libre espace jeux pour les tout petits et ludoth\u00e8que \u00e0 dispo pour les plus grands. Points de collectes pour les midis du Mie et Un petit bagage d\u2019amour &nbsp; Mardi \u00e0 Pantin : 19\/21h Boxe Anglaise f\u00e9minine avec Audrey et sa team (prix libre) 19\/21h Conf\u00e9rence d\u00e9bat avec le collectif \u00ab\u00a0Nous sommes Pantin\u00a0\u00bb sur les th\u00e8mes suivants : logement, immobilier, gentrification, sp\u00e9culation. &nbsp; Jeudi \u00e0 Pantin : Distribution de l\u2019AMAP des 4 chemin 18\/20h atelier d\u2019auto-r\u00e9paration et de construction avec Michel \u00a0tawashis minis et g\u00e9ants en autonomie boissons chaudes\/gouter\/cantoch\u2019 bio \u00e0 prix libre espace jeux pour les tout petits et ludoth\u00e8que \u00e0 dispo pour les plus grands. Points de collectes pour les midis du Mie et Un petit bagage d\u2019amour ET : Suite de nos soir\u00e9es de soutien aux gr\u00e9vistes, RDV \u00e0 20h30 pour le film et cantoch bio \u00e0 prix libre cette semaine : Diffusion de \u00ab\u00a0l&rsquo;amour et la r\u00e9volution\u00a0\u00bb de Yannis Youlountas. Super premi\u00e8re \u00e9dition hier soir, une trentaine de personnes et 178,60 euros de r\u00e9colt\u00e9s ! On fera mieux la semaine prochaine, on compte sur vous !!! Passez l&rsquo;info, venez nombreux. &nbsp; Belle semaine \u00e0 toutes\/s<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"rop_custom_images_group":[],"rop_custom_messages_group":[],"rop_publish_now":"initial","rop_publish_now_accounts":[],"rop_publish_now_history":[],"rop_publish_now_status":"pending","_themeisle_gutenberg_block_has_review":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[1],"tags":[],"class_list":["post-1221","post","type-post","status-publish","format-standard","hentry","category-non-classe"],"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1203,"url":"https:\/\/www.labozero.org\/index.php\/2020\/01\/10\/la-programmation-de-la-semaine\/","url_meta":{"origin":1221,"position":0},"title":"La programmation de la semaine","author":"labozero","date":"10 janvier, 2020","format":false,"excerpt":"On se retrouve demain, Samedi\u00a0 chez les copains du DSXL pour une apr\u00e8s midi avec Gratuiterie, atelier d'auto-r\u00e9paration, go\u00fbter \u00e0 prix libre, jeux... RDV \u00e0 15h\u00a0 au 101 avenue Gaston Roussel \u00e0 Romainville. Dimanche 15\/21 RDv au 20 avenue edouard vaillant \u00e0 Pantin pour : 15\/21h atelier d'auto-r\u00e9paration et de\u2026","rel":"","context":"Dans &quot;Non class\u00e9&quot;","block_context":{"text":"Non class\u00e9","link":"https:\/\/www.labozero.org\/index.php\/category\/non-classe\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.labozero.org\/wp-content\/uploads\/2020\/01\/fullsizer-150x150.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.labozero.org\/wp-content\/uploads\/2020\/01\/fullsizer-150x150.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.labozero.org\/wp-content\/uploads\/2020\/01\/fullsizer-150x150.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":1184,"url":"https:\/\/www.labozero.org\/index.php\/2020\/01\/03\/bonne-annee\/","url_meta":{"origin":1221,"position":1},"title":"Bonne Ann\u00e9e !","author":"labozero","date":"3 janvier, 2020","format":false,"excerpt":"Et oui, bonne ann\u00e9e \u00e0 toutes\/s ! \u00a0 Nous d\u00e9butons l'ann\u00e9e avec plein de projets et des nouveaut\u00e9s ! D\u00e9j\u00e0 Audrey et sa team proposent un second atelier boxe Anglaise f\u00e9minine \u00e0 prix libre le mardi soir entre 19 et 21h \u00e0 Pantin. Cela commence d\u00e8s la semaine prochaine. Un\u2026","rel":"","context":"Dans &quot;Non class\u00e9&quot;","block_context":{"text":"Non class\u00e9","link":"https:\/\/www.labozero.org\/index.php\/category\/non-classe\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.labozero.org\/wp-content\/uploads\/2020\/01\/0061d170-2b74-4c50-ab86-d856ae467d5d-150x150.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.labozero.org\/wp-content\/uploads\/2020\/01\/0061d170-2b74-4c50-ab86-d856ae467d5d-150x150.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.labozero.org\/wp-content\/uploads\/2020\/01\/0061d170-2b74-4c50-ab86-d856ae467d5d-150x150.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.labozero.org\/wp-content\/uploads\/2020\/01\/0061d170-2b74-4c50-ab86-d856ae467d5d-150x150.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":1737,"url":"https:\/\/www.labozero.org\/index.php\/2020\/09\/23\/des-news-et-la-prog-de-cette-semaine\/","url_meta":{"origin":1221,"position":2},"title":"Des news et la prog&rsquo; de cette semaine","author":"labozero","date":"23 septembre, 2020","format":false,"excerpt":"Tout d'abord des nouvelles du proc\u00e8s en cours avec l'EPFIF : l'audience initialement pr\u00e9vue le 17 a \u00e9t\u00e9 report\u00e9e au 22 septembre mais n'y \u00e9taient convi\u00e9s que les deux avocats car notre super justicier a trouv\u00e9 des irr\u00e9gularit\u00e9s dans les \u00e9critures de notre adversaire... Nous en saurons plus le 6\u2026","rel":"","context":"Dans &quot;Non class\u00e9&quot;","block_context":{"text":"Non class\u00e9","link":"https:\/\/www.labozero.org\/index.php\/category\/non-classe\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.labozero.org\/wp-content\/uploads\/2020\/09\/20200913_172431.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.labozero.org\/wp-content\/uploads\/2020\/09\/20200913_172431.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.labozero.org\/wp-content\/uploads\/2020\/09\/20200913_172431.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.labozero.org\/wp-content\/uploads\/2020\/09\/20200913_172431.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.labozero.org\/wp-content\/uploads\/2020\/09\/20200913_172431.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":1231,"url":"https:\/\/www.labozero.org\/index.php\/2020\/01\/25\/dans-la-jungle-des-cigognes-des-bebes-et-du-soleil\/","url_meta":{"origin":1221,"position":3},"title":"Dans la jungle : des cigognes, des b\u00e9b\u00e9s et du soleil !","author":"labozero","date":"25 janvier, 2020","format":false,"excerpt":"Les nouveaut\u00e9s pleuvent en ce d\u00e9but d'ann\u00e9e ! Un atelier jardinage\/permaculture en int\u00e9rieur ou comment cr\u00e9er une jungle dans un entrep\u00f4t ? Une vraie permanence des cigognes d'un petit bagage d'amour \u00e0 Pantin et la premi\u00e8re date des ateliers mamans b\u00e9b\u00e9s ! Je vous raconte tout \u00e7a en d\u00e9tail :\u2026","rel":"","context":"Dans &quot;Non class\u00e9&quot;","block_context":{"text":"Non class\u00e9","link":"https:\/\/www.labozero.org\/index.php\/category\/non-classe\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.labozero.org\/wp-content\/uploads\/2020\/01\/external-2content.duckduckgo.com_-150x150.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.labozero.org\/wp-content\/uploads\/2020\/01\/external-2content.duckduckgo.com_-150x150.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.labozero.org\/wp-content\/uploads\/2020\/01\/external-2content.duckduckgo.com_-150x150.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.labozero.org\/wp-content\/uploads\/2020\/01\/external-2content.duckduckgo.com_-150x150.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":1009,"url":"https:\/\/www.labozero.org\/index.php\/2019\/10\/11\/vive-la-paresse\/","url_meta":{"origin":1221,"position":4},"title":"Vive la paresse !","author":"labozero","date":"11 octobre, 2019","format":false,"excerpt":"Samedi on se retrouve \u00e0 la friche de Noisy-le-sec, qui pour ceux qui ne le savent pas encore, est en danger, faute de soutien de la mairie, p\u00e9tition de soutien \u00e0 venir tr\u00e8s vite ! Donc 15\/17h Gratuiterie Ambulante et jardinage avec Michel car je serai pour ma part \u00e0\u2026","rel":"","context":"Dans &quot;Non class\u00e9&quot;","block_context":{"text":"Non class\u00e9","link":"https:\/\/www.labozero.org\/index.php\/category\/non-classe\/"},"img":{"alt_text":"image001-3","src":"https:\/\/i0.wp.com\/www.labozero.org\/wp-content\/uploads\/2019\/10\/image001-3.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.labozero.org\/wp-content\/uploads\/2019\/10\/image001-3.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.labozero.org\/wp-content\/uploads\/2019\/10\/image001-3.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.labozero.org\/wp-content\/uploads\/2019\/10\/image001-3.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":1328,"url":"https:\/\/www.labozero.org\/index.php\/2020\/02\/18\/1328\/","url_meta":{"origin":1221,"position":5},"title":"La prog de la semaine","author":"labozero","date":"18 f\u00e9vrier, 2020","format":false,"excerpt":"Une fois encore la temp\u00eate a jou\u00e9 contre nous... d\u00e9sol\u00e9s pour cette fermeture de dimanche, le soleil est de retour et nous aussi ! Les nouveaut\u00e9s : des perm's de pr\u00e9paration pour Un petit bagage d'amour les mardis de 14 \u00e0 18h, pour devenir cigogne les inscriptions se font sur\u2026","rel":"","context":"Dans &quot;Non class\u00e9&quot;","block_context":{"text":"Non class\u00e9","link":"https:\/\/www.labozero.org\/index.php\/category\/non-classe\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.labozero.org\/wp-content\/uploads\/2020\/02\/streetpress-documentaire-gilet-jaune-represssion-etat.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.labozero.org\/wp-content\/uploads\/2020\/02\/streetpress-documentaire-gilet-jaune-represssion-etat.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.labozero.org\/wp-content\/uploads\/2020\/02\/streetpress-documentaire-gilet-jaune-represssion-etat.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.labozero.org\/wp-content\/uploads\/2020\/02\/streetpress-documentaire-gilet-jaune-represssion-etat.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.labozero.org\/wp-content\/uploads\/2020\/02\/streetpress-documentaire-gilet-jaune-represssion-etat.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]}],"jetpack_shortlink":"https:\/\/wp.me\/pbPs9A-jH","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.labozero.org\/index.php\/wp-json\/wp\/v2\/posts\/1221","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.labozero.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.labozero.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.labozero.org\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.labozero.org\/index.php\/wp-json\/wp\/v2\/comments?post=1221"}],"version-history":[{"count":0,"href":"https:\/\/www.labozero.org\/index.php\/wp-json\/wp\/v2\/posts\/1221\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.labozero.org\/index.php\/wp-json\/wp\/v2\/media?parent=1221"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.labozero.org\/index.php\/wp-json\/wp\/v2\/categories?post=1221"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.labozero.org\/index.php\/wp-json\/wp\/v2\/tags?post=1221"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}